{"id":7312,"date":"2026-05-11T15:39:34","date_gmt":"2026-05-11T13:39:34","guid":{"rendered":"https:\/\/asfaltart.it\/strassenkunst-festival-meran\/r-e-d\/"},"modified":"2026-05-11T15:40:39","modified_gmt":"2026-05-11T13:40:39","slug":"r-e-d","status":"publish","type":"portfolio","link":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/","title":{"rendered":"R.E.D."},"content":{"rendered":"<div class='flex_column_table av-4bnq18-54978f3e1365ef6bff25683666b616d9 sc-av_one_third av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4bnq18-54978f3e1365ef6bff25683666b616d9\">\n.flex_column.av-4bnq18-54978f3e1365ef6bff25683666b616d9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-4bnq18-54978f3e1365ef6bff25683666b616d9 av_one_third  avia-builder-el-0  avia-builder-el-no-sibling  first flex_column_table_cell av-equal-height-column av-align-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mp18ynu2-5eac7d925380634867cf5e365d2920df\">\n.avia-image-container.av-mp18ynu2-5eac7d925380634867cf5e365d2920df img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-mp18ynu2-5eac7d925380634867cf5e365d2920df .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-mp18ynu2-5eac7d925380634867cf5e365d2920df av-styling- av-img-linked avia-align-left  avia-builder-el-1  el_before_av_hr  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg\" data-srcset=\"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg 1030w, https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red-300x200.jpg 300w, https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red-768x512.jpg 768w, https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red-705x470.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='red'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-7313 avia-img-lazy-loading-not-7313 avia_image ' src=\"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg\" alt='r.e.d.' title='red'  height=\"687\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg 1030w, https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red-300x200.jpg 300w, https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red-768x512.jpg 768w, https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red-705x470.jpg 705w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-36nllo-bdd5751fca8ea19e5d469e4289e6631e\">\n#top .hr.hr-invisible.av-36nllo-bdd5751fca8ea19e5d469e4289e6631e{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-36nllo-bdd5751fca8ea19e5d469e4289e6631e hr-invisible  avia-builder-el-2  el_after_av_image  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-mp18z7eo-f7b18dc7ba2afc0c3449541467f071c3 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>R.E.D. (IT)<\/h2>\n<h4>La pi\u00f9 belle<br \/>\nComedy &amp; circus<\/h4>\n<p>Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata dall\u2018unione del capitale umano di un italo-spagnolo, un italo-argentino e di un italo-napoletano\u2026 riuniti sotto un nome inglese. Cos\u00ec Rodrigo, Eddy e Diego hanno incrociato le loro esperienze personali per dare vita, moltiplicando gli effetti, allo spettacolo \u201eLa pi\u00f9 belle\u201c coinvolgendo il proprio pubblico e arrivando alla pancia dello spettatore.<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata dall\u2018unione del capitale &#8230;<\/p>\n","protected":false},"author":1,"featured_media":7313,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[542],"class_list":["post-7312","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-r-e-d"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R.E.D. - asfaltart<\/title>\n<meta name=\"description\" content=\"R.E.D.: Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R.E.D. - asfaltart\" \/>\n<meta property=\"og:description\" content=\"R.E.D.: Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/\" \/>\n<meta property=\"og:site_name\" content=\"asfaltart\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asfaltart\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T13:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@asfaltartmerano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/\",\"url\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/\",\"name\":\"R.E.D. - asfaltart\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asfaltart.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/red.jpg\",\"datePublished\":\"2026-05-11T13:39:34+00:00\",\"dateModified\":\"2026-05-11T13:40:39+00:00\",\"description\":\"R.E.D.: Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asfaltart.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/red.jpg\",\"contentUrl\":\"https:\\\/\\\/asfaltart.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/red.jpg\",\"width\":1030,\"height\":687,\"caption\":\"r.e.d.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/festival-arte-di-strada-merano\\\/r-e-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R.E.D.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/\",\"name\":\"asfaltart\",\"description\":\"Festival d'Arte di Strada Merano, Alto Adige - Italia\",\"publisher\":{\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/#organization\",\"name\":\"asfaltart\",\"url\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asfaltart.it\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/asfaltart_credits.png\",\"contentUrl\":\"https:\\\/\\\/asfaltart.it\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/asfaltart_credits.png\",\"width\":1030,\"height\":687,\"caption\":\"asfaltart\"},\"image\":{\"@id\":\"https:\\\/\\\/asfaltart.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asfaltart\",\"https:\\\/\\\/x.com\\\/asfaltartmerano\",\"https:\\\/\\\/www.instagram.com\\\/asfaltartfestivalmerano\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R.E.D. - asfaltart","description":"R.E.D.: Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/","og_locale":"it_IT","og_type":"article","og_title":"R.E.D. - asfaltart","og_description":"R.E.D.: Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata ...","og_url":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/","og_site_name":"asfaltart","article_publisher":"https:\/\/www.facebook.com\/asfaltart","article_modified_time":"2026-05-11T13:40:39+00:00","og_image":[{"width":1030,"height":687,"url":"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@asfaltartmerano","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/","url":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/","name":"R.E.D. - asfaltart","isPartOf":{"@id":"https:\/\/asfaltart.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/#primaryimage"},"image":{"@id":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/#primaryimage"},"thumbnailUrl":"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg","datePublished":"2026-05-11T13:39:34+00:00","dateModified":"2026-05-11T13:40:39+00:00","description":"R.E.D.: Pionieri dell\u2019arte di strada in Italia, gruppo anomalo nel panorama. Sono infatti una \u201cmultinazionale\u201d dello spettacolo nata ...","breadcrumb":{"@id":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/#primaryimage","url":"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg","contentUrl":"https:\/\/asfaltart.it\/wp-content\/uploads\/2026\/05\/red.jpg","width":1030,"height":687,"caption":"r.e.d."},{"@type":"BreadcrumbList","@id":"https:\/\/asfaltart.it\/it\/festival-arte-di-strada-merano\/r-e-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/asfaltart.it\/it\/"},{"@type":"ListItem","position":2,"name":"R.E.D."}]},{"@type":"WebSite","@id":"https:\/\/asfaltart.it\/it\/#website","url":"https:\/\/asfaltart.it\/it\/","name":"asfaltart","description":"Festival d'Arte di Strada Merano, Alto Adige - Italia","publisher":{"@id":"https:\/\/asfaltart.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asfaltart.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/asfaltart.it\/it\/#organization","name":"asfaltart","url":"https:\/\/asfaltart.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/asfaltart.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/asfaltart.it\/wp-content\/uploads\/2021\/05\/asfaltart_credits.png","contentUrl":"https:\/\/asfaltart.it\/wp-content\/uploads\/2021\/05\/asfaltart_credits.png","width":1030,"height":687,"caption":"asfaltart"},"image":{"@id":"https:\/\/asfaltart.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asfaltart","https:\/\/x.com\/asfaltartmerano","https:\/\/www.instagram.com\/asfaltartfestivalmerano\/"]}]}},"_links":{"self":[{"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/portfolio\/7312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/comments?post=7312"}],"version-history":[{"count":4,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/portfolio\/7312\/revisions"}],"predecessor-version":[{"id":7316,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/portfolio\/7312\/revisions\/7316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/media\/7313"}],"wp:attachment":[{"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/media?parent=7312"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/tags?post=7312"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/asfaltart.it\/it\/wp-json\/wp\/v2\/portfolio_entries?post=7312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}